{"id":94894,"date":"2024-01-30T08:27:09","date_gmt":"2024-01-30T14:27:09","guid":{"rendered":"https:\/\/programadestinosmexico.com\/?page_id=94894"},"modified":"2025-02-14T16:45:39","modified_gmt":"2025-02-14T22:45:39","slug":"iglesia-de-santiago-merida","status":"publish","type":"page","link":"https:\/\/programadestinosmexico.com\/en\/iglesia-de-santiago-merida\/","title":{"rendered":"Iglesia de Santiago\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"94894\" class=\"elementor elementor-94894\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3890a1 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"d3890a1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6472743\" data-id=\"6472743\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4f8fae elementor-hidden-mobile elementor-widget elementor-widget-jet-slider\" data-id=\"c4f8fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-c4f8fae&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-c4f8fae&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-c4f8fae hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-c4f8fae hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2024\/01\/IGLESIA-DE-SANTIAGO1.jpg\" alt=\"IGLESIA DE SANTIAGO1\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23e1f65 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"23e1f65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-534cd37\" data-id=\"534cd37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5b1718 elementor-widget elementor-widget-jet-slider\" data-id=\"a5b1718\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-a5b1718&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-a5b1718&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-a5b1718 hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-a5b1718 hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2024\/01\/IGLESIA-DE-SANTIAGO1.jpg\" alt=\"IGLESIA DE SANTIAGO1\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1279f8c e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1279f8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78e5c27 elementor-widget elementor-widget-jet-accordion\" data-id=\"78e5c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\"jet-accordion__item jet-toggle jet-toggle-move-up-effect\">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1261\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1261\" aria-expanded=\"false\" data-template-id=\"4477\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">EXPLORING THE WONDERS OF COLONIAL ARCHITECTURE IN MEXICO<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1261\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"4477\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4477\" class=\"elementor elementor-4477\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-e1f3ade elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"e1f3ade\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d7ea833 e-con-full e-flex e-con e-child\" data-id=\"d7ea833\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-a77a6ab e-flex e-con-boxed e-con e-child\" data-id=\"a77a6ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0f781 elementor-widget elementor-widget-heading\" data-id=\"7b0f781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/golf\/los-cabos.html\">Campeche<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2e26a elementor-widget elementor-widget-image\" data-id=\"de2e26a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-campeche\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"425\" height=\"282\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-CAMPECHE.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2433\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-CAMPECHE.jpg 425w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-CAMPECHE-300x199.jpg 300w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-069a833 e-flex e-con-boxed e-con e-child\" data-id=\"069a833\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5feab6 elementor-widget elementor-widget-heading\" data-id=\"c5feab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/golf\/cancun.html\">Mexico City<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d8e8d8 elementor-widget elementor-widget-image\" data-id=\"9d8e8d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5765\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5acbee5 e-flex e-con-boxed e-con e-child\" data-id=\"5acbee5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70f1b88 elementor-widget elementor-widget-heading\" data-id=\"70f1b88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tlaxcala<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2feecea elementor-widget elementor-widget-image\" data-id=\"2feecea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tlaxcala\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"425\" height=\"282\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-TLAXCALA.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2437\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-TLAXCALA.jpg 425w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/04\/ARQUITECTURA-COLONIAL-TLAXCALA-300x199.jpg 300w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-017e748 e-con-full e-flex e-con e-child\" data-id=\"017e748\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-fc0f478 e-flex e-con-boxed e-con e-child\" data-id=\"fc0f478\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2230571 e-con-full e-flex e-con e-child\" data-id=\"2230571\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f3461c elementor-widget elementor-widget-heading\" data-id=\"7f3461c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2845dd elementor-widget elementor-widget-html\" data-id=\"c2845dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california\/\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california\/\">Sitios Misionales<\/a><\/li>\n     \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california-sur\/\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california-sur\/\">Sitios Misionales<\/a><\/li>\n          \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-chihuahua\/\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-chihuahua\/\">Chihuahua<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-saltillo\/\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-saltillo\/\">Saltillo<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-durango\/\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-durango\/\">Durango<\/a><\/li>\n   \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-zacatecas\/\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a82c19c e-con-full e-flex e-con e-child\" data-id=\"a82c19c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80da567 elementor-widget elementor-widget-heading\" data-id=\"80da567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e979d elementor-widget elementor-widget-html\" data-id=\"e3e979d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-aguascalientes\/\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-aguascalientes\/\">Aguascalientes<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-toluca\/\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-toluca\/\">Toluca<\/a><\/li>\n  \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guanajuato\/\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-celaya\/\">Celaya<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guanajuato\/\">Guanajuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-irapuato\/\">Irapuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-leon\/\"\">Le\u00f3n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-miguel-de-allende\/\">San Miguel de Allende<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-pachuca\/\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-pachuca\/\">Pachuca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guadalajara\/\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guadalajara\/\">Guadalajara<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-morelia\/\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-morelia\/\">Morelia<\/a><\/li>\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-patzcuaro\/\">P\u00e1tzcuaro<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuernavaca\/\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n  <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuautla\/\">Cuautla<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuernavaca\/\"\">Cuernavaca y alrededores<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tepic\/\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n        <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tepic\/\">Tepic<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-puebla\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-puebla\/\">Puebla<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tehuacan\/\">Tehuac\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-queretaro\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-misiones-de-la-sierra-gorda-en-queretaro\/\">Misiones de la Sierra Gorda<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-luis-potosi\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tlaxcala\/\">Tlaxcala<i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-veracruz\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cordoba\/\">C\u00f3rdoba<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-orizaba\/\">Orizaba<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-veracruz\/\">Veracruz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-xalapa\/\">Xalapa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fecd82a e-con-full e-flex e-con e-child\" data-id=\"fecd82a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb59dfa elementor-widget elementor-widget-heading\" data-id=\"cb59dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a68c6dd elementor-widget elementor-widget-html\" data-id=\"a68c6dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-campeche\/\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-campeche\/\">Campeche<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-cristobal-de-las-casas\/\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-cristobal-de-las-casas\/\"> San Crist\u00f3bal de las Casas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-taxco\/\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-taxco-6\/\">Taxco<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-oaxaca\/\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-oaxaca\/\">Oaxaca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-merida\/\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-merida\/\">M\u00e9rida<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-valladolid\/\">Valladolid,<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a66ed7a elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"a66ed7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8e81318 e-con-full e-flex e-con e-child\" data-id=\"8e81318\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-08f867e e-flex e-con-boxed e-con e-child\" data-id=\"08f867e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be62de4 elementor-widget elementor-widget-heading\" data-id=\"be62de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Morelos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba6c38b elementor-widget elementor-widget-image\" data-id=\"ba6c38b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuernavaca\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11764\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-MORELOS-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02368dd e-flex e-con-boxed e-con e-child\" data-id=\"02368dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ca30c elementor-widget elementor-widget-heading\" data-id=\"f6ca30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mexico City<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f767aa7 elementor-widget elementor-widget-image\" data-id=\"f767aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5765\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-CIUDAD-DE-MEXICO-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-879fbf6 e-flex e-con-boxed e-con e-child\" data-id=\"879fbf6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-495f14e elementor-widget elementor-widget-heading\" data-id=\"495f14e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Guanajuato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3ae6de elementor-widget elementor-widget-image\" data-id=\"f3ae6de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guanajuato\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"439\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-GUANAJUATO.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2460\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-GUANAJUATO.jpg 661w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/ARQUITECTURA-COLONIAL-GUANAJUATO-300x199.jpg 300w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa0d64d e-con-full e-flex e-con e-child\" data-id=\"aa0d64d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2ac5c27 e-con-full e-flex e-con e-child\" data-id=\"2ac5c27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5e12471 e-con-full e-flex e-con e-child\" data-id=\"5e12471\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1d4fa3 elementor-widget elementor-widget-heading\" data-id=\"e1d4fa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96ceadd elementor-widget elementor-widget-html\" data-id=\"96ceadd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california\/\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california\/\">Sitios Misionales<\/a><\/li>\n     \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california-sur\/\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-baja-california-sur\/\">Sitios Misionales<\/a><\/li>\n          \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-chihuahua\/\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-chihuahua\/\">Chihuahua<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-saltillo\/\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-saltillo\/\">Saltillo<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-durango\/\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-durango\/\">Durango<\/a><\/li>\n   \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-zacatecas\/\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7aa2917 e-con-full e-flex e-con e-child\" data-id=\"7aa2917\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-12ecf8c e-con-full e-flex e-con e-child\" data-id=\"12ecf8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-edec5c8 e-con-full e-flex e-con e-child\" data-id=\"edec5c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a16b4d elementor-widget elementor-widget-heading\" data-id=\"9a16b4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d9de5a elementor-widget elementor-widget-html\" data-id=\"1d9de5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-aguascalientes\/\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-aguascalientes\/\">Aguascalientes<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-la-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-toluca\/\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-toluca\/\">Toluca<\/a><\/li>\n  \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guanajuato\/\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-celaya\/\">Celaya<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guanajuato\/\">Guanajuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-irapuato\/\">Irapuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-leon\/\"\">Le\u00f3n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-miguel-de-allende\/\">San Miguel de Allende<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-pachuca\/\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-pachuca\/\">Pachuca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guadalajara\/\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-guadalajara\/\">Guadalajara<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-morelia\/\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-morelia\/\">Morelia<\/a><\/li>\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-patzcuaro\/\">P\u00e1tzcuaro<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuernavaca\/\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n  <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuautla\/\">Cuautla<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cuernavaca\/\"\">Cuernavaca y alrededores<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tepic\/\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n        <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tepic\/\">Tepic<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-puebla\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-puebla\/\">Puebla<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tehuacan\/\">Tehuac\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-queretaro\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-misiones-de-la-sierra-gorda-en-queretaro\/\">Misiones de la Sierra Gorda<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-luis-potosi\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tlaxcala\/\">Tlaxcala<i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-veracruz\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-cordoba\/\">C\u00f3rdoba<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-orizaba\/\">Orizaba<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-veracruz\/\">Veracruz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-xalapa\/\">Xalapa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d43077 e-con-full e-flex e-con e-child\" data-id=\"6d43077\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-4817877 e-con-full e-flex e-con e-child\" data-id=\"4817877\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-047bd58 elementor-widget elementor-widget-heading\" data-id=\"047bd58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff9c837 elementor-widget elementor-widget-html\" data-id=\"ff9c837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-campeche\/\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-campeche\/\">Campeche<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-cristobal-de-las-casas\/\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-san-cristobal-de-las-casas\/\"> San Crist\u00f3bal de las Casas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-taxco\/\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-taxco\/\">Taxco<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-oaxaca\/\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-oaxaca\/\">Oaxaca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-merida\/\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-merida\/\">M\u00e9rida<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/arquitectura-colonial-en-valladolid\/\">Valladolid,<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7969ed4 e-flex e-con-boxed e-con e-parent\" data-id=\"7969ed4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4510d2a e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"4510d2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d62a184 elementor-widget elementor-widget-heading\" data-id=\"d62a184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">It is located in the first indigenous town that the conquerors found when they arrived at T'ho, which they named Santiago.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72841d5 elementor-widget elementor-widget-text-editor\" data-id=\"72841d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>It is the place where the first mass in the city was celebrated, as stated on a plaque inside the church.<\/p><p>According to the engraving located at the entrance, the church was completed in 1637.<\/p><p>It has a beautiful facade with a door framed by an arch. Inside, its magnificent altarpieces stand out, especially the one dedicated to Santiago Ap\u00f3stol, made of wood.<\/p><p>It is located in a beautiful square where the program \"Musical Remembrances\" takes place every Tuesday night, featuring old melodies that bring together many local residents and national and foreign tourists.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ecef27 e-flex e-con-boxed e-con e-child\" data-id=\"8ecef27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-51e1238 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"51e1238\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02e7670 elementor-widget elementor-widget-heading\" data-id=\"02e7670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Location\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-969e9e9 elementor-widget elementor-widget-text-editor\" data-id=\"969e9e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Calle 70 x 57 y 59, Centro, M\u00e9rida, Yuc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9fe77e e-con-full e-flex e-con e-child\" data-id=\"d9fe77e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21acdef elementor-widget elementor-widget-heading\" data-id=\"21acdef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Iglesia de Santiago <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f773f1e elementor-widget elementor-widget-image\" data-id=\"f773f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"591\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/Iglesia-de-Santiago-.jpg\" class=\"attachment-large size-large wp-image-43317\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/Iglesia-de-Santiago-.jpg 591w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/Iglesia-de-Santiago--300x300.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f03ac4b e-flex e-con-boxed e-con e-parent\" data-id=\"f03ac4b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3c29d4 elementor-widget elementor-widget-heading\" data-id=\"f3c29d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.civitatis.com\/mx\/merida-mexico\/\" target=\"_blank\" rel=\"noopener\">M\u00e9rida Top Tours &amp; Activities<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1edc5e e-flex e-con-boxed e-con e-parent\" data-id=\"c1edc5e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0af0764 elementor-widget elementor-widget-heading\" data-id=\"0af0764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\">PLAN YOUR TRIP<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56a5204 e-flex e-con-boxed e-con e-parent\" data-id=\"56a5204\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e001f33 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"e001f33\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d0ed1 elementor-widget elementor-widget-image\" data-id=\"23d0ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reservar.programadestinosmexico.com\/merida\/hoteles\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6778\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-DONDE-HOSPEDARSE-1-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-573fc63 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"573fc63\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a465b4 elementor-widget elementor-widget-heading\" data-id=\"3a465b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/merida\/hoteles\">Where to stay in M\u00e9rida<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76f0ddf elementor-widget elementor-widget-heading\" data-id=\"76f0ddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/merida\/hoteles\">Up to<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e91ffa elementor-widget elementor-widget-heading\" data-id=\"5e91ffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/merida\/hoteles\">30%<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2735a19 elementor-widget elementor-widget-heading\" data-id=\"2735a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/merida\/hoteles\">Off<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75060d0 e-flex e-con-boxed e-con e-parent\" data-id=\"75060d0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4370952 elementor-widget elementor-widget-heading\" data-id=\"4370952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\">TAKE ADVANTAGE OF THE BEST OFFERS<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c9d4bc e-flex e-con-boxed e-con e-parent\" data-id=\"1c9d4bc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49384e0 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"49384e0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e46e2b elementor-widget elementor-widget-image\" data-id=\"7e46e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-merida\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"471\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-2.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6780\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-2.jpg 709w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MERIDA-2-300x199.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-344261f e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"344261f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-088fab6 elementor-widget elementor-widget-heading\" data-id=\"088fab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-merida\/\">WHAT TO SEE &amp; DO IN M\u00c9RIDA<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd1fceb elementor-widget elementor-widget-text-editor\" data-id=\"dd1fceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>WHITE CITY EMBRACED BY THE MAYA WORLD<\/p><h2>\u00a0<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d49e04 e-flex e-con-boxed e-con e-parent\" data-id=\"5d49e04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bdf58dc e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"bdf58dc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-313d558 elementor-widget elementor-widget-image\" data-id=\"313d558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-yucatan\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"471\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/ARQUITECTURA-COLONIAL-YUCATAN.jpg\" class=\"attachment-medium_large size-medium_large wp-image-43942\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/ARQUITECTURA-COLONIAL-YUCATAN.jpg 709w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/10\/ARQUITECTURA-COLONIAL-YUCATAN-300x199.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1950518 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"1950518\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a67d837 elementor-widget elementor-widget-heading\" data-id=\"a67d837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-yucatan\/\">Download your Free Travel Guide<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-305da6e elementor-widget elementor-widget-text-editor\" data-id=\"305da6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>and enjoy an unforgettable vacation<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdedcba elementor-widget elementor-widget-jet-button\" data-id=\"fdedcba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-right hover-effect-0\" href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-yucatan\/\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DESCUBRE LA ARQUITECTURA COLONIAL POR DESTINO Campeche Ciudad de M\u00e9xico Tlaxcala Norte Men\u00fa desplegable personalizable Baja California Sitios Misionales Baja California Sur Sitios Misionales Chihuahua Chihuahua Coahuila Saltillo Durango Durango Zacatecas Zacatecas Centro Men\u00fa desplegable personalizable Aguascalientes Aguascalientes Ciudad de M\u00e9xico Ciudad de M\u00e9xico Estado de M\u00e9xico Toluca Guanajuato Celaya Guanajuato Irapuato<\/p>","protected":false},"author":2,"featured_media":43316,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-94894","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/94894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/comments?post=94894"}],"version-history":[{"count":8,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/94894\/revisions"}],"predecessor-version":[{"id":157926,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/94894\/revisions\/157926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media\/43316"}],"wp:attachment":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media?parent=94894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}