{"id":70418,"date":"2023-12-19T12:37:22","date_gmt":"2023-12-19T18:37:22","guid":{"rendered":"https:\/\/programadestinosmexico.com\/?page_id=70418"},"modified":"2024-07-03T10:07:49","modified_gmt":"2024-07-03T16:07:49","slug":"historia-de-cozumel","status":"publish","type":"page","link":"https:\/\/programadestinosmexico.com\/en\/historia-de-cozumel\/","title":{"rendered":"History in Cozumel"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"70418\" class=\"elementor elementor-70418\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-262f7890 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"262f7890\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c27901e\" data-id=\"c27901e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ee1e0ba elementor-hidden-mobile elementor-widget elementor-widget-jet-slider\" data-id=\"2ee1e0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-2ee1e0ba&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-2ee1e0ba&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-2ee1e0ba hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-2ee1e0ba hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/historia-de-cozumel-1-scaled.jpg\" alt=\"historia de cozumel 1\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e863563 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"e863563\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58a9126\" data-id=\"58a9126\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e20300 elementor-widget elementor-widget-jet-slider\" data-id=\"4e20300\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-4e20300&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-4e20300&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-4e20300 hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-4e20300 hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/historia-de-cozumel-1-scaled.jpg\" alt=\"historia de cozumel 1\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-132f90e e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"132f90e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a31832 elementor-widget elementor-widget-jet-accordion\" data-id=\"2a31832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\"jet-accordion__item jet-toggle jet-toggle-move-up-effect\">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-4421\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-4421\" aria-expanded=\"false\" data-template-id=\"12013\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">DISCOVER THE HISTORY OF MEXICO<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-4421\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"12013\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"12013\" class=\"elementor elementor-12013\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-45894ec elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"45894ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-041746e e-con-full e-flex e-con e-child\" data-id=\"041746e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-1b87233 e-flex e-con-boxed e-con e-child\" data-id=\"1b87233\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3e8fd4 elementor-widget elementor-widget-heading\" data-id=\"c3e8fd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of Guadalajara<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f4b8c elementor-widget elementor-widget-image\" data-id=\"c6f4b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guadalajara\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"709\" height=\"471\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12014\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA.jpg 709w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA-300x199.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1818c99 e-flex e-con-boxed e-con e-child\" data-id=\"1818c99\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1414ca5 elementor-widget elementor-widget-heading\" data-id=\"1414ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of M\u00e9rida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e2eba elementor-widget elementor-widget-image\" data-id=\"e1e2eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-merida\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12016\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ac3ffb e-flex e-con-boxed e-con e-child\" data-id=\"7ac3ffb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb217cc elementor-widget elementor-widget-heading\" data-id=\"bb217cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of Oaxaca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df0e675 elementor-widget elementor-widget-image\" data-id=\"df0e675\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-oaxaca\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12018\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a39f68 e-con-full e-flex e-con e-child\" data-id=\"9a39f68\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-8d653a4 e-flex e-con-boxed e-con e-child\" data-id=\"8d653a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33ffd1a e-con-full e-flex e-con e-child\" data-id=\"33ffd1a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-462ab36 elementor-widget elementor-widget-heading\" data-id=\"462ab36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-674f8b5 elementor-widget elementor-widget-html\" data-id=\"674f8b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ensenada\/\">Ensenada<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-rosarito\/\">Rosarito<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tijuana\/\">Tijuana<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-la-paz\/\">La Paz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-loreto\/\">Loreto<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-los-cabos\/\">Los Cabos<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-chihuahua\/\">Chihuahua<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ciudad-juarez\/\">Ciudad Ju\u00e1rez<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-saltillo\/\">Saltillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-durango\/\">Durango<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Nuevo Le\u00f3n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-monterrey\/\">Monterrey<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Sinaloa <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-mazatlan\/\">Mazatl\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Sonora <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-hermosillo\/\">Hermosillo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Tamaulipas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tampico\/\">Tampico<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce82d73 e-con-full e-flex e-con e-child\" data-id=\"ce82d73\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d880c7 elementor-widget elementor-widget-heading\" data-id=\"9d880c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fbabb4 elementor-widget elementor-widget-html\" data-id=\"2fbabb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-aguascalientes\/\">Aguascalientes<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-la-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Colima <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-colima\/\">Colima<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-manzanillo\/\">Manzanillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-toluca\/\">Toluca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-valle-de-bravo\/\">Valle de Bravo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guanajuato\/\">Guanajuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-leon\/\">Le\u00f3n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-miguel-de-allende\/\">San Miguel de Allende<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-pachuca\/\">Pachuca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guadalajara\/\">Guadalajara<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puerto-vallarta\/\">Puerto Vallarta<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-morelia\/\">Morelia<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-patzcuaro\/\">P\u00e1tzcuaro<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cuernavaca\/\">Cuernavaca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tepic\/\">Tepic<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puebla-3\/\">Puebla<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Tlaxcala <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    \n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-boca-del-rio\/\">Boca del R\u00edo<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-veracruz\/\">Veracruz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-xalapa\/\">Xalapa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bca8d8 e-con-full e-flex e-con e-child\" data-id=\"6bca8d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17b8347 elementor-widget elementor-widget-heading\" data-id=\"17b8347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d23edc elementor-widget elementor-widget-html\" data-id=\"6d23edc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-campeche\/\">Campeche<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ciudad-del-carmen\/\">Ciudad del Carmen<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-cristobal-de-las-casas\/\">San Crist\u00f3bal de las Casas<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tuxtla-gutierrez\/\">Tuxtla Guti\u00e9rrez<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-acapulco\/\">Acapulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ixtapa-zihuatanejo\/\">Ixtapa - Zihuatanejo <\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-taxco\/\">Taxco <\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-huatulco\/\">Huatulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-oaxaca\/\">Oaxaca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puerto-escondido\/\">Puerto Escondido<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Quintana Roo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cancun\/\">Canc\u00fan<\/a><\/li>\n    <li><a href=\"http:\/\/programadestinosmexico.com\/en\/historia-de-chetumal\/\">Chetumal<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cozumel\/\">Cozumel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-isla-mujeres\/\">Isla Mujeres<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-riviera-maya\/\">Riviera Maya<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Tabasco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-villahermosa\/\">Villahermosa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-merida\/\">M\u00e9rida<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f9e06f elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"4f9e06f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59fcff0 e-con-full e-flex e-con e-child\" data-id=\"59fcff0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-7535d09 e-flex e-con-boxed e-con e-child\" data-id=\"7535d09\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98ae9f0 elementor-widget elementor-widget-heading\" data-id=\"98ae9f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of Guadalajara<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9c6785 elementor-widget elementor-widget-image\" data-id=\"c9c6785\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guadalajara\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"709\" height=\"471\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12014\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA.jpg 709w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-GUADALAJARA-300x199.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f09693 e-flex e-con-boxed e-con e-child\" data-id=\"8f09693\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0eb7e43 elementor-widget elementor-widget-heading\" data-id=\"0eb7e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of M\u00e9rida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-616357f elementor-widget elementor-widget-image\" data-id=\"616357f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-merida\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12016\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-MERIDA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ee1cb8 e-flex e-con-boxed e-con e-child\" data-id=\"2ee1cb8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-140b281 elementor-widget elementor-widget-heading\" data-id=\"140b281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">History of Oaxaca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14f4f84 elementor-widget elementor-widget-image\" data-id=\"14f4f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-oaxaca\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12018\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/HISTORIA-OAXACA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8dfaf5 e-con-full e-flex e-con e-child\" data-id=\"d8dfaf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-c89bec8 e-con-full e-flex e-con e-child\" data-id=\"c89bec8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2d21916 e-con-full e-flex e-con e-child\" data-id=\"2d21916\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-f306a10 e-con-full e-flex e-con e-child\" data-id=\"f306a10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b9286b elementor-widget elementor-widget-heading\" data-id=\"2b9286b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ead2684 elementor-widget elementor-widget-html\" data-id=\"ead2684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ensenada\/\">Ensenada<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-rosarito\/\">Rosarito<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tijuana\/\">Tijuana<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-la-paz\/\">La Paz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-loreto\/\">Loreto<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-los-cabos\/\">Los Cabos<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-chihuahua\/\">Chihuahua<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ciudad-juarez\/\">Ciudad Ju\u00e1rez<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-saltillo\/\">Saltillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-durango\/\">Durango<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Nuevo Le\u00f3n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-monterrey\/\">Monterrey<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Sinaloa <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-mazatlan\/\">Mazatl\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Sonora <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-hermosillo\/\">Hermosillo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Tamaulipas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tampico\/\">Tampico<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-512d685 e-con-full e-flex e-con e-child\" data-id=\"512d685\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-40ccaaa e-con-full e-flex e-con e-child\" data-id=\"40ccaaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-db61ffd e-con-full e-flex e-con e-child\" data-id=\"db61ffd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf44f07 elementor-widget elementor-widget-heading\" data-id=\"cf44f07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338474d elementor-widget elementor-widget-html\" data-id=\"338474d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-aguascalientes\/\">Aguascalientes<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-la-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Colima <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-colima\/\">Colima<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-manzanillo\/\">Manzanillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-toluca\/\">Toluca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-valle-de-bravo\/\">Valle de Bravo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guanajuato\/\">Guanajuato<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-leon\/\">Le\u00f3n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-miguel-de-allende\/\">San Miguel de Allende<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-pachuca\/\">Pachuca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-guadalajara\/\">Guadalajara<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puerto-vallarta\/\">Puerto Vallarta<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-morelia\/\">Morelia<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-patzcuaro\/\">P\u00e1tzcuaro<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cuernavaca\/\">Cuernavaca<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tepic\/\">Tepic<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puebla-3\/\">Puebla<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Tlaxcala <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    \n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\/en\/xxxxxx\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-boca-del-rio\/\">Boca del R\u00edo<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-veracruz\/\">Veracruz<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-xalapa\/\">Xalapa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6584265 e-con-full e-flex e-con e-child\" data-id=\"6584265\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-7a1bc8b e-con-full e-flex e-con e-child\" data-id=\"7a1bc8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8be0f0 elementor-widget elementor-widget-heading\" data-id=\"d8be0f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-591d377 elementor-widget elementor-widget-html\" data-id=\"591d377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-campeche\/\">Campeche<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ciudad-del-carmen\/\">Ciudad del Carmen<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-san-cristobal-de-las-casas\/\">San Crist\u00f3bal de las Casas<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-tuxtla-gutierrez\/\">Tuxtla Guti\u00e9rrez<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-acapulco\/\">Acapulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-ixtapa-zihuatanejo\/\">Ixtapa - Zihuatanejo <\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-taxco\/\">Taxco <\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-huatulco\/\">Huatulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-oaxaca\/\">Oaxaca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-puerto-escondido\/\">Puerto Escondido<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Quintana Roo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cancun\/\">Canc\u00fan<\/a><\/li>\n    <li><a href=\"http:\/\/programadestinosmexico.com\/en\/historia-de-chetumal\/\">Chetumal<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-cozumel\/\">Cozumel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-isla-mujeres\/\">Isla Mujeres<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-riviera-maya\/\">Riviera Maya<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Tabasco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-villahermosa\/\">Villahermosa<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/historia-de-merida\/\">M\u00e9rida<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7969ed4 e-flex e-con-boxed e-con e-parent\" data-id=\"7969ed4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4510d2a e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"4510d2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d62a184 elementor-widget elementor-widget-heading\" data-id=\"d62a184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">A PILGRIMAGE SITE TO WORSHIP IXCHEL<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72841d5 elementor-widget elementor-widget-text-editor\" data-id=\"72841d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cozumel is a Mayan word that means \"Land of the Swallows,\" as this bird is very common in the region.<\/p><p>Recent research has proven that the first Mayan settlers established themselves in Cozumel approximately 2,000 years ago.<\/p><p>The remains of these glorious days can be found in the archaeological sites of El Cedral, El Caracol, and San Gervacio, the most important ceremonial center. During the Postclassic period, the Mayans used the island as a place to worship Ixchel, the goddess of fertility.<\/p><p>In 1518, Juan de Grijalva was the first Spanish explorer to reach the island. The following year, Hern\u00e1n Cort\u00e9s landed on these shores and met the only survivor of a previous shipwrecked expedition, Jer\u00f3nimo de Aguilar. Cort\u00e9s took Aguilar with him during the rest of the conquest as an interpreter.<\/p><p>When Cort\u00e9s left Cozumel, the ancient civilization was already in ruins. Additionally, the few remaining inhabitants were infected with smallpox, which almost wiped out the native population. Between 1519 and 1570, the island's population decreased from 40,000 to 30. As a result, the island remained forgotten and only served as a refuge for some pirates.<\/p><p>During World War II, the United States built an airbase in Cozumel and used its crystal-clear waters as a training ground for their frogmen. This brought attention to the island's natural wonders.<\/p><p>Later on, the oceanographer Jacques Cousteau proclaimed Cozumel as one of the best diving spots in the world, which helped establish it as one of the top diving destinations globally.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9fe77e e-con-full e-flex e-con e-child\" data-id=\"d9fe77e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21acdef elementor-widget elementor-widget-heading\" data-id=\"21acdef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">History in Cozumel<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f773f1e elementor-widget elementor-widget-image\" data-id=\"f773f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-70318\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/12\/HISTORIA-COZUMEL-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c3dd2a e-flex e-con-boxed e-con e-parent\" data-id=\"2c3dd2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0f1e67d e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"0f1e67d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f93d27 elementor-widget elementor-widget-image\" data-id=\"4f93d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/donde-hospedarse\/cozumel.html\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4218\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-DONDE-HOSPEDARSE-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49c322c e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"49c322c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb44d3 elementor-widget elementor-widget-heading\" data-id=\"3fb44d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/donde-hospedarse\/cozumel.html\">Where to Stay in Cozumel<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7622595 e-flex e-con-boxed e-con e-parent\" data-id=\"7622595\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1477b2d e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"1477b2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c33d4f elementor-widget elementor-widget-image\" data-id=\"2c33d4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-chetumal\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"471\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2296\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL.jpg 709w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/COZUMEL-300x199.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42b6dad e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"42b6dad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99a5b47 elementor-widget elementor-widget-heading\" data-id=\"99a5b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-chetumal\/\">WHAT TO SEE &amp; DO IN COZUMEL<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6b69dd elementor-widget elementor-widget-text-editor\" data-id=\"c6b69dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A UNIQUE UNDERWATER PARADISE<\/p><h2>\u00a0<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-762df54 e-flex e-con-boxed e-con e-parent\" data-id=\"762df54\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7aae654 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"7aae654\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a885289 elementor-widget elementor-widget-image\" data-id=\"a885289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-mexico\/costa-maya-guia\/GRAN%20COSTA%20MAYA%202019-%206.pdf\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"439\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/BUCEO-EN-COZUMEL.jpg\" class=\"attachment-large size-large wp-image-2669\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/BUCEO-EN-COZUMEL.jpg 661w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/BUCEO-EN-COZUMEL-300x199.jpg 300w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5527c9 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"e5527c9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcaf69c elementor-widget elementor-widget-heading\" data-id=\"fcaf69c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-mexico\/costa-maya-guia\/GRAN%20COSTA%20MAYA%202019-%206.pdf\/\">Download your Free Travel Guide<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541664f elementor-widget elementor-widget-text-editor\" data-id=\"541664f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>and enjoy an unforgettable vacation<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dc9220 elementor-widget elementor-widget-jet-button\" data-id=\"0dc9220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-right hover-effect-0\" href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-mexico\/costa-maya-guia\/GRAN%20COSTA%20MAYA%202019-%206.pdf\/\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DESCUBRE LA HISTORIA DE LOS DESTINOS TUR\u00cdSTICOS Historia de Guadalajara Historia de M\u00e9rida Historia de Oaxaca Norte Men\u00fa desplegable personalizable Baja California Ensenada Rosarito Tijuana Baja California Sur La Paz Loreto Los Cabos Chihuahua Chihuahua Ciudad Ju\u00e1rez Coahuila Saltillo Durango Durango Nuevo Le\u00f3n Monterrey Sinaloa Mazatl\u00e1n Sonora Hermosillo Tamaulipas Tampico Zacatecas Zacatecas Centro Men\u00fa desplegable [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":70318,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-70418","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/70418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/comments?post=70418"}],"version-history":[{"count":12,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/70418\/revisions"}],"predecessor-version":[{"id":133911,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/70418\/revisions\/133911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media\/70318"}],"wp:attachment":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media?parent=70418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}