{"id":58528,"date":"2023-11-19T11:29:14","date_gmt":"2023-11-19T17:29:14","guid":{"rendered":"https:\/\/programadestinosmexico.com\/?page_id=58528"},"modified":"2025-05-15T11:48:48","modified_gmt":"2025-05-15T17:48:48","slug":"montanismo-en-durango","status":"publish","type":"page","link":"https:\/\/programadestinosmexico.com\/en\/montanismo-en-durango\/","title":{"rendered":"Mountain Climbing in Durango"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"58528\" class=\"elementor elementor-58528\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-262f7890 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"262f7890\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c27901e\" data-id=\"c27901e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d928c7 elementor-hidden-mobile elementor-widget elementor-widget-jet-slider\" data-id=\"9d928c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-9d928c7&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-9d928c7&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-9d928c7 hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-9d928c7 hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/11\/Montanismo-en-Durango.jpg\" alt=\"Montanismo en Durango\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9267529 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"9267529\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfb6444\" data-id=\"dfb6444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04414bd elementor-widget elementor-widget-jet-slider\" data-id=\"04414bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slider_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;slider_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slider_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-slider jet-elements\">\n<div class=\"jet-slider jet-slider__image-exact\" data-settings='{&quot;sliderWidth&quot;:1,&quot;sliderHeight&quot;:1,&quot;sliderNavigation&quot;:false,&quot;sliderNavigationIcon&quot;:&quot;jet-slider__arrow-icon-04414bd&quot;,&quot;sliderNaviOnHover&quot;:false,&quot;sliderPagination&quot;:false,&quot;sliderAutoplay&quot;:true,&quot;sliderAutoplayDelay&quot;:5000,&quot;sliderAutoplayOnHover&quot;:&quot;pause&quot;,&quot;sliderFullScreen&quot;:false,&quot;sliderFullscreenIcon&quot;:&quot;jet-slider__fullscreen-icon-04414bd&quot;,&quot;sliderShuffle&quot;:false,&quot;sliderLoop&quot;:true,&quot;sliderFadeMode&quot;:false,&quot;slideDistance&quot;:1,&quot;slideDuration&quot;:500,&quot;imageScaleMode&quot;:&quot;exact&quot;,&quot;thumbnails&quot;:false,&quot;thumbnailWidth&quot;:120,&quot;thumbnailHeight&quot;:80,&quot;rightToLeft&quot;:false,&quot;touchswipe&quot;:true,&quot;fractionPag&quot;:false,&quot;fractionPrefix&quot;:&quot;&quot;,&quot;fractionSeparator&quot;:&quot;\\\/&quot;,&quot;fractionSuffix&quot;:&quot;&quot;,&quot;autoSliderHeight&quot;:false}'>\n\t\n<div  class=\"slider-pro\">\n\t<div class=\"jet-slider__arrow-icon-04414bd hidden-html\"><\/div><div class=\"jet-slider__fullscreen-icon-04414bd hidden-html\"><\/div>\t<div class=\"jet-slider__items sp-slides\">\n\n\n<div  class=\"jet-slider__item sp-slide elementor-repeater-item-c8b6f42\"><img decoding=\"async\" class=\"sp-image\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/11\/Montanismo-en-Durango.jpg\" alt=\"Montanismo en Durango\" loading=\"lazy\"><div class=\"jet-slider__content sp-layer\" data-position=\"centerCenter\" data-width=\"100%\" data-height=\"100%\" data-horizontal=\"0%\" data-show-transition=\"up\" data-show-duration=\"400\" data-show-delay=\"400\" >\n\t\t<div class=\"jet-slider__content-item\">\n\t\t\t<div class=\"jet-slider__content-inner\"> \n\n\t\t\t\t\t\t<div class=\"jet-slider__button-wrapper\">\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-65190fb e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"65190fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bded561 elementor-widget elementor-widget-jet-accordion\" data-id=\"bded561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\"jet-accordion__item jet-toggle jet-toggle-move-up-effect\">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1991\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1991\" aria-expanded=\"false\" data-template-id=\"11795\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">BEST DESTINATIONS FOR ADVENTURE<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1991\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"11795\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"11795\" class=\"elementor elementor-11795\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-4296085 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4296085\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d25776 e-con-full e-flex e-con e-child\" data-id=\"5d25776\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-036528b e-flex e-con-boxed e-con e-child\" data-id=\"036528b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38f8f03 elementor-widget elementor-widget-heading\" data-id=\"38f8f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/aventura-y-ecoturismo\/buceo-en-cozumel.html\">Diving in Cozumel<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc8a4da elementor-widget elementor-widget-image\" data-id=\"fc8a4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/buceo-en-cozumel\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11796\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c79c3e7 e-flex e-con-boxed e-con e-child\" data-id=\"c79c3e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe3f339 elementor-widget elementor-widget-heading\" data-id=\"fe3f339\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/aventura-y-ecoturismo\/surf-en-baja-california.html\">Surfing in Baja California<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c3e43 elementor-widget elementor-widget-image\" data-id=\"a6c3e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/surf-en-baja-california\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11798\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9c8b51 e-flex e-con-boxed e-con e-child\" data-id=\"a9c8b51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3718c28 elementor-widget elementor-widget-heading\" data-id=\"3718c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/aventura-y-ecoturismo\/kayak-en-campeche.html\">Kayak in Campeche<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ea66a elementor-widget elementor-widget-image\" data-id=\"19ea66a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/kayak-en-campeche\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11800\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4394ad e-con-full e-flex e-con e-child\" data-id=\"a4394ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-649cb71 e-flex e-con-boxed e-con e-child\" data-id=\"649cb71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27b7e74 e-con-full e-flex e-con e-child\" data-id=\"27b7e74\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4be316b elementor-widget elementor-widget-heading\" data-id=\"4be316b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03d8170 elementor-widget elementor-widget-html\" data-id=\"03d8170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-baja-california\/\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-baja-california\/\">Baja California<\/a><\/li>\n    \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-los-cabos\/\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-la-paz\/\">La Paz<\/a><\/li>\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-loreto\/\">Loreto<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-los-cabos\/\">Los Cabos<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chihuahua\/\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chihuahua\/\">Chihuahua<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-coahuila\/\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-coahuila\/\">Coahuila<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-durango\/\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-durango\/\">Durango<\/a><\/li>\n    \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-nuevo-leon\/\">Nuevo Le\u00f3n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-nuevo-leon\/\">Nuevo Le\u00f3n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sinaloa\/\">Sinaloa <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-mazatlan\/\">Mazatl\u00e1n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sinaloa\/\">Sinaloa<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/aventura-y-ecoturismo\/sonora.html\">Sonora <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-penasco\/\">Rocky Point<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-carlos\/\">San Carlos<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sonora\/\">Sonora<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tamaulipas\/\">Tamaulipas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tamaulipas\/\">Tamaulipas<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-zacatecas\/\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6030751 e-con-full e-flex e-con e-child\" data-id=\"6030751\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f9f97 elementor-widget elementor-widget-heading\" data-id=\"d8f9f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cbe892 elementor-widget elementor-widget-html\" data-id=\"4cbe892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-aguascalientes\/\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-aguascalientes\/\">Aguascalientes<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ciudad-de-mexico\/\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-colima\/\">Colima <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-colima\/\">Colima<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-manzanillo\/\">Manzanillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-el-estado-de-mexico\/\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-el-estado-de-mexico\/\">Estado de M\u00e9xico<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guanajuato\/\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guanajuato\/\">Guanajuato<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-hidalgo\/\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-hidalgo\/\">Hidalgo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guadalajara\/\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-costalegre\/\">Costalegre<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guadalajara\/\">Guadalajara<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-vallarta\/\">Puerto Vallarta<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-michoacan\/\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-michoacan\/\">Michoac\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-morelos\/\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-morelos\/\">Morelos<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-nayarit\/\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-nayarit\/\">Riviera Nayarit<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puebla\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puebla\/\">Puebla<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-queretaro\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n  \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-luis-potosi\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tlaxcala\/\">Tlaxcala <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-veracruz\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-veracruz\/\">Veracruz<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc3266b e-con-full e-flex e-con e-child\" data-id=\"bc3266b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f92052a elementor-widget elementor-widget-heading\" data-id=\"f92052a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b2dc6f elementor-widget elementor-widget-html\" data-id=\"2b2dc6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-campeche\/\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-campeche\/\">Campeche<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chiapas\/\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chiapas\/\">Chiapas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-acapulco\/\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-acapulco\/\">Acapulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ixtapa-zihuatanejo\/\">Ixtapa - Zihuatanejo <\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-taxco\/\">Taxco<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-oaxaca\/\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-huatulco\/\">Huatulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-oaxaca\/\">Oaxaca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-angel\/\">Puerto \u00c1ngel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-escondido\/\">Puerto Escondido<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cancun\/\">Quintana Roo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cancun\/\">Canc\u00fan<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cozumel\/\">Cozumel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-costa-maya\/\">Costa Maya<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-isla-mujeres\/\">Isla Mujeres<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-maya\/\">Riviera Maya<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tabasco\/\">Tabasco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tabasco\/\">Tabasco<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-yucatan\/\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-yucatan\/\">Yucat\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47de4e2 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"47de4e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03f5b02 e-con-full e-flex e-con e-child\" data-id=\"03f5b02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-d8eefaa e-flex e-con-boxed e-con e-child\" data-id=\"d8eefaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69f1568 elementor-widget elementor-widget-heading\" data-id=\"69f1568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diving in Cozumel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8970f3 elementor-widget elementor-widget-image\" data-id=\"a8970f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/buceo-en-cozumel\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11796\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-QUINTANA-ROO-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba33ecd e-flex e-con-boxed e-con e-child\" data-id=\"ba33ecd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64b2c08 elementor-widget elementor-widget-heading\" data-id=\"64b2c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Surfing in Baja California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acf4731 elementor-widget elementor-widget-image\" data-id=\"acf4731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/surf-en-baja-california\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11798\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-BAJA-CALIFORNIA-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5065178 e-flex e-con-boxed e-con e-child\" data-id=\"5065178\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-155ce76 elementor-widget elementor-widget-heading\" data-id=\"155ce76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kayak in Campeche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-021fd08 elementor-widget elementor-widget-image\" data-id=\"021fd08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/en\/kayak-en-campeche\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11800\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-CAMPECHE-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03da807 e-con-full e-flex e-con e-child\" data-id=\"03da807\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-a78528a e-con-full e-flex e-con e-child\" data-id=\"a78528a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-8cc07e3 e-con-full e-flex e-con e-child\" data-id=\"8cc07e3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e96b6d elementor-widget elementor-widget-heading\" data-id=\"7e96b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Northern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8bad28 elementor-widget elementor-widget-html\" data-id=\"f8bad28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-baja-california\/\">Baja California <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-baja-california\/\">Baja California<\/a><\/li>\n    \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-los-cabos\/\">Baja California Sur <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-la-paz\/\">La Paz<\/a><\/li>\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-loreto\/\">Loreto<\/a><\/li>\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-los-cabos\/\">Los Cabos<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chihuahua\/\">Chihuahua <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chihuahua\/\">Chihuahua<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-coahuila\/\">Coahuila <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-coahuila\/\">Coahuila<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-durango\/\">Durango <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-durango\/\">Durango<\/a><\/li>\n    \n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-nuevo-leon\/\">Nuevo Le\u00f3n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-nuevo-leon\/\">Nuevo Le\u00f3n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sinaloa\/\">Sinaloa <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-mazatlan\/\">Mazatl\u00e1n<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sinaloa\/\">Sinaloa<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/aventura-y-ecoturismo\/sonora.html\">Sonora <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-penasco\/\">Rocky Point<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-carlos\/\">San Carlos<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-sonora\/\">Sonora<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tamaulipas\/\">Tamaulipas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tamaulipas\/\">Tamaulipas<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-zacatecas\/\">Zacatecas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-zacatecas\/\">Zacatecas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07e7d14 e-con-full e-flex e-con e-child\" data-id=\"07e7d14\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5b76823 e-con-full e-flex e-con e-child\" data-id=\"5b76823\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-517bb79 elementor-widget elementor-widget-heading\" data-id=\"517bb79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Central Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaae3f1 elementor-widget elementor-widget-html\" data-id=\"eaae3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-aguascalientes\/\">Aguascalientes <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-aguascalientes\/\">Aguascalientes<\/a><\/li>\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ciudad-de-mexico\/\">Mexico City <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ciudad-de-mexico\/\">Mexico City<\/a><\/li>\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-colima\/\">Colima <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n     <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-colima\/\">Colima<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-manzanillo\/\">Manzanillo<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-el-estado-de-mexico\/\">Estado de M\u00e9xico <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-el-estado-de-mexico\/\">Estado de M\u00e9xico<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guanajuato\/\">Guanajuato <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guanajuato\/\">Guanajuato<\/a><\/li>\n    \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-hidalgo\/\">Hidalgo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-hidalgo\/\">Hidalgo<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guadalajara\/\">Jalisco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-costalegre\/\">Costalegre<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-guadalajara\/\">Guadalajara<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-vallarta\/\">Puerto Vallarta<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-michoacan\/\">Michoac\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-michoacan\/\">Michoac\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-morelos\/\">Morelos <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-morelos\/\">Morelos<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-nayarit\/\">Nayarit <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-nayarit\/\">Riviera Nayarit<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puebla\/\">Puebla <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puebla\/\">Puebla<\/a><\/li>\n\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-queretaro\/\">Quer\u00e9taro <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-queretaro\/\">Quer\u00e9taro<\/a><\/li>\n  \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-luis-potosi\/\">San Luis Potos\u00ed <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-san-luis-potosi\/\">San Luis Potos\u00ed<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tlaxcala\/\">Tlaxcala <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tlaxcala\/\">Tlaxcala<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-veracruz\/\">Veracruz <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-veracruz\/\">Veracruz<\/a><\/li>\n   \n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-112b114 e-con-full e-flex e-con e-child\" data-id=\"112b114\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-9c635e7 e-con-full e-flex e-con e-child\" data-id=\"9c635e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffda331 elementor-widget elementor-widget-heading\" data-id=\"ffda331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Southern Mexico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc44d0b elementor-widget elementor-widget-html\" data-id=\"fc44d0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n<meta charset=\"UTF-8\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n<title>Men\u00fa desplegable personalizable<\/title>\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" crossorigin=\"anonymous\" \/>\n<style>\n  body {\n    font-family: Arial, sans-serif;\n  }\n\n  .menu-principal {\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 200px;\n  }\n\n  .menu-item {\n    position: relative;\n  }\n\n  .menu-item a {\n    display: block;\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .menu-item a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .sub-menu {\n    display: none;\n    position: relative;\n    list-style-type: none;\n    margin: 0;\n    padding: 0;\n    background-color: #33333300;\n    width: 100%;\n  }\n\n  .sub-menu a {\n    padding: 8px 16px;\n    color: #5E5E5E;\n    text-decoration: none;\n    line-height: 14px; \/* Cambiado aqu\u00ed *\/\n  }\n\n  .sub-menu a:hover {\n    background-color: #11111100;\n    color: #B7BEA0;\n  }\n\n  .menu-item:hover .sub-menu {\n    display: block;\n  }\n\n<\/style>\n<\/head>\n<body>\n\n<ul class=\"menu-principal\">\n  <li class=\"menu-item\">\n    <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-campeche\/\">Campeche <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n    <ul class=\"sub-menu\">\n      <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-campeche\/\">Campeche<\/a><\/li>\n\n      <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n    <\/ul>\n  <\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chiapas\/\">Chiapas <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-chiapas\/\">Chiapas<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-acapulco\/\">Guerrero <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-acapulco\/\">Acapulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-ixtapa-zihuatanejo\/\">Ixtapa - Zihuatanejo <\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-taxco\/\">Taxco<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-oaxaca\/\">Oaxaca <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-huatulco\/\">Huatulco<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-oaxaca\/\">Oaxaca<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-angel\/\">Puerto \u00c1ngel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-puerto-escondido\/\">Puerto Escondido<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cancun\/\">Quintana Roo <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cancun\/\">Canc\u00fan<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-cozumel\/\">Cozumel<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-costa-maya\/\">Costa Maya<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-isla-mujeres\/\">Isla Mujeres<\/a><\/li>\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-riviera-maya\/\">Riviera Maya<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tabasco\/\">Tabasco <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-tabasco\/\">Tabasco<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<li class=\"menu-item\">\n  <a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-yucatan\/\">Yucat\u00e1n <i class=\"fas fa-angle-right desplegable\"><\/i><\/a>\n  <ul class=\"sub-menu\">\n    <li><a href=\"https:\/\/programadestinosmexico.com\/en\/aventura-y-ecoturismo-en-yucatan\/\">Yucat\u00e1n<\/a><\/li>\n    <!-- Agrega m\u00e1s elementos de submen\u00fa aqu\u00ed -->\n  <\/ul>\n<\/li>\n<\/ul>\n\n<script>\n  const menuItems = document.querySelectorAll(\".menu-item\");\n  \n  menuItems.forEach(menuItem => {\n    menuItem.addEventListener(\"mouseenter\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-right\");\n        icono.classList.add(\"fa-angle-down\");\n      }\n    });\n\n    menuItem.addEventListener(\"mouseleave\", () => {\n      const icono = menuItem.querySelector(\".desplegable\");\n      if (icono) {\n        icono.classList.remove(\"fa-angle-down\");\n        icono.classList.add(\"fa-angle-right\");\n      }\n    });\n  });\n<\/script>\n<\/body>\n<\/html>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10062b9 e-flex e-con-boxed e-con e-parent\" data-id=\"10062b9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d12f86 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"4d12f86\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a33364 elementor-widget elementor-widget-text-editor\" data-id=\"4a33364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><strong>DURANGO<\/strong><\/em><\/p><p>Among the most recommended sites for mountaineers are the Alto Tarabilla hill, shortly before reaching Los Altares, which has an altitude of 2860 meter over the sea level, and the famous Los Monos hill, 8 km southeast of the town of Sapioris, with its steep vertical walls that reach 2600 meters above sea level.<\/p><p>It is located 241 km, approximately 4 hours from the city of Durango.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9cde6a e-con-full e-flex e-con e-child\" data-id=\"e9cde6a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64f85f3 elementor-widget elementor-widget-heading\" data-id=\"64f85f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Mountain Climbing in Durango<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cabf6a1 elementor-widget elementor-widget-image\" data-id=\"cabf6a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"591\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/11\/Campismo-en-Durango-1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-58465\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/11\/Campismo-en-Durango-1.jpg 591w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/11\/Campismo-en-Durango-1-300x300.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48a27a2 e-flex e-con-boxed e-con e-parent\" data-id=\"48a27a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df392d7 elementor-widget elementor-widget-heading\" data-id=\"df392d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.civitatis.com\/es\/buscar?q=durango\" target=\"_blank\" rel=\"noopener\">Explora los Mejores Tours a DURANGO con ofertas todos los d\u00edas<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-347803e e-flex e-con-boxed e-con e-parent\" data-id=\"347803e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b117e0 elementor-widget elementor-widget-heading\" data-id=\"3b117e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\">PLAN YOUR TRIP<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca42e26 e-flex e-con-boxed e-con e-parent\" data-id=\"ca42e26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-10c338e e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"10c338e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4bb176 elementor-widget elementor-widget-image\" data-id=\"f4bb176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reservar.programadestinosmexico.com\/durango\/hoteles\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6058\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-DONDE-HOSPEDARSE-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-291deca e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"291deca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c56154 elementor-widget elementor-widget-heading\" data-id=\"1c56154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/durango\/hoteles\">Where to stay in Durango<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-129928e elementor-widget elementor-widget-heading\" data-id=\"129928e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/durango\/hoteles\">Up to<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3295e elementor-widget elementor-widget-heading\" data-id=\"9e3295e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/durango\/hoteles\">25%<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-134aa00 elementor-widget elementor-widget-heading\" data-id=\"134aa00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\/durango\/hoteles\">Off<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44fbec6 e-flex e-con-boxed e-con e-parent\" data-id=\"44fbec6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bff3950 elementor-widget elementor-widget-heading\" data-id=\"bff3950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reservar.programadestinosmexico.com\">TAKE ADVANTAGE OF THE BEST OFFERS<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f43bc9f e-con-full e-flex e-con e-parent\" data-id=\"f43bc9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2d77f1b e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"2d77f1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a63c8b elementor-widget elementor-widget-heading\" data-id=\"1a63c8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 MUST VISIT DESTINATIONS IN DURANGO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccd4d01 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"ccd4d01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60366c0 imgzoom elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"60366c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-durango\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-300x199.jpg\" class=\"attachment-medium size-medium wp-image-6040\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/DURANGO.jpg 709w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-durango\/\">Durango<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6957c98 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"6957c98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d01e3 imgzoom elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b9d01e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-nombre-de-dios\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/PUEBLOS-MAGICOS-NOMBRE-DE-DIOS-300x199.jpg\" class=\"attachment-medium size-medium wp-image-8068\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/PUEBLOS-MAGICOS-NOMBRE-DE-DIOS-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/PUEBLOS-MAGICOS-NOMBRE-DE-DIOS.jpg 709w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-nombre-de-dios\/\">Nombre de Dios<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d56485 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"8d56485\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-841687a imgzoom elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"841687a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-mapimi\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI-300x199.jpg\" class=\"attachment-medium size-medium wp-image-11021\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/08\/MAPIMI.jpg 1654w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/programadestinosmexico.com\/en\/que-ver-y-hacer-en-mapimi\/\">Mapim\u00ed<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b7c7fb e-flex e-con-boxed e-con e-parent\" data-id=\"9b7c7fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9669bd7 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"9669bd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-222b7b1 elementor-widget elementor-widget-image\" data-id=\"222b7b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/programadestinosmexico.com\/guias-turisticas-de-mexico.html\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"510\" src=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-768x510.jpg\" class=\"attachment-medium_large size-medium_large wp-image-12935\" alt=\"\" srcset=\"https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-768x510.jpg 768w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-300x199.jpg 300w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-1024x680.jpg 1024w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-1536x1020.jpg 1536w, https:\/\/programadestinosmexico.com\/wp-content\/uploads\/2023\/09\/AVENTURA-Y-ECOTURISMO-DURANGO-2048x1360.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ced3f56 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"ced3f56\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa0b10 elementor-widget elementor-widget-heading\" data-id=\"4aa0b10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-mexico\/\">Download your Free Travel Guide<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37fe0d3 elementor-widget elementor-widget-text-editor\" data-id=\"37fe0d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>and enjoy an unforgettable vacation<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6efc4ac elementor-widget elementor-widget-jet-button\" data-id=\"6efc4ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-right hover-effect-0\" href=\"https:\/\/programadestinosmexico.com\/en\/guias-turisticas-de-mexico\/\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/span><span class=\"jet-button__label\">Click Here<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Entre los sitios m\u00e1s recomendados para el monta\u00f1ista, se encuentran el cerro Alto Tarabilla.<br \/>\nAmong the most recommended sites for mountaineers are the Alto Tarabilla hill.<\/p>","protected":false},"author":2,"featured_media":58465,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-58528","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/58528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/comments?post=58528"}],"version-history":[{"count":12,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/58528\/revisions"}],"predecessor-version":[{"id":168726,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/pages\/58528\/revisions\/168726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media\/58465"}],"wp:attachment":[{"href":"https:\/\/programadestinosmexico.com\/en\/wp-json\/wp\/v2\/media?parent=58528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}